{"id":878,"date":"2009-02-18T18:37:35","date_gmt":"2009-02-18T17:37:35","guid":{"rendered":"http:\/\/sironimo.com\/\/?p=878"},"modified":"2010-04-15T18:39:51","modified_gmt":"2010-04-15T16:39:51","slug":"derniers-films-vus-part-1","status":"publish","type":"post","link":"https:\/\/sironimo.com\/index.php\/2009\/02\/18\/derniers-films-vus-part-1\/","title":{"rendered":"Derniers films vus (part 1)"},"content":{"rendered":"<p>Olalalla c&rsquo;est catastrophique&#8230; Avant je parlais un peu des films que j&rsquo;allais voir au cin\u00e9 ou m\u00eame des films vus en DVD ou \u00e0 la t\u00e9l\u00e9, j&rsquo;avais m\u00eame cr\u00e9er <a title=\"Bobine de fil'm\" href=\"http:\/\/sironimo.blogs.allocine.fr\/\" target=\"_blank\">un blog sp\u00e9cialement pour \u00e7a<\/a>. Et puis, j&rsquo;ai eu l&rsquo;impression que ce que je racontais sur les films \u00e9tait absolument sans int\u00e9r\u00eat, et, m\u00eame une review de trois lignes, j&rsquo;ai trouv\u00e9 \u00e7a trop fatigant \u00e0 faire! -__-.<\/p>\n<p>Je dois me reprendre en main crotte! J&rsquo;aime les films, j&rsquo;aime le cin\u00e9, j&rsquo;ai le droit d&rsquo;en parler un minimum, m\u00eame si ce que je peux dire sur un film ne semble pas tr\u00e8s int\u00e9ressant \u00e0 premi\u00e8re vue.<\/p>\n<p>Voila, je m&rsquo;y remets d\u00e8s maintenant avec les films que j&rsquo;ai vu r\u00e9cemment et je commence par ceux vus \u00e0 <strong>Paris<\/strong> :<\/p>\n<p style=\"text-align: center;\"><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/bon_brute_cingle.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-885\" title=\"bon_brute_cingle\" src=\"\/wp-content\/images\/2009\/02\/bon_brute_cingle-150x150.jpg\" alt=\"bon_brute_cingle\" width=\"150\" height=\"150\" \/><\/a> <a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/simpson_film.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-938\" title=\"simpson_film\" src=\"\/wp-content\/images\/2009\/02\/simpson_film-150x150.jpg\" alt=\"simpson_film\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/clock_groundhog_day.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-935\" title=\"clock_groundhog_day\" src=\"\/wp-content\/images\/2009\/02\/clock_groundhog_day-150x150.jpg\" alt=\"clock_groundhog_day\" width=\"150\" height=\"150\" \/><\/a> <a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/little_miss_sunshine02.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-933\" title=\"little_miss_sunshine02\" src=\"\/wp-content\/images\/2009\/02\/little_miss_sunshine02-150x150.jpg\" alt=\"little_miss_sunshine02\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><!--more--><br \/>\n<strong>\u25ba <a title=\"the good the bad the weird - Official website\" href=\"http:\/\/www.thegoodthebadtheweird.co.uk\" target=\"_blank\">Le Bon, La Brute, Le Cingl\u00e9<\/a><\/strong> (<em>Joheunnom nabbeunnom isanghannom<\/em>)<\/p>\n<p><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/the-good-the-bad-and-the-weird.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-932\" title=\"the-good-the-bad-and-the-weird\" src=\"\/wp-content\/images\/2009\/02\/the-good-the-bad-and-the-weird-150x150.jpg\" alt=\"the-good-the-bad-and-the-weird\" width=\"150\" height=\"150\" \/><\/a><br \/>\nJ&rsquo;aime beaucoup les westerns, tout comme les films de sabre japonais ou autres grandes aventures solitaires, h\u00e9ro\u00efques et dangereuses. J&rsquo;ai vu tous les grands westerns spaghetti dans mon enfance et j&rsquo;ai pris plaisir \u00e0 les revoir plus r\u00e9cemment pour en saisir toutes les subtilit\u00e9s.<\/p>\n<p>Les cadrages, la musique, la tension palpable qui r\u00e8gne dans certaines sc\u00e8nes et toute cette atmosph\u00e8re me plait vraiment. On retrouve \u00e9galement tout \u00e7a dans les films de sabre, de samurai, de <em>yakuza<\/em> voir m\u00eame dans <strong>Star Wars<\/strong> (qui est inspir\u00e9 par de vieux films japonais rappelons le).<\/p>\n<p>R\u00e9cemment, la sc\u00e8ne fa\u00e7on <em>western<\/em> de <strong>Pirates des Cara\u00efbes 3 (jusqu&rsquo;au bout du monde)<\/strong> m&rsquo;a donn\u00e9 des frisons. Le western est un genre qui revient lentement \u00e0 la mode, r\u00e9cup\u00e9r\u00e9 notamment par les asiatiques et je m&rsquo;attendais d&rsquo;ailleurs \u00e0 voir d\u00e9barquer en <em>France<\/em><strong>, Sukiyaki Western Django<\/strong>, le western japonais de <strong>Takashi Miike<\/strong>. Mais apparemment ce n&rsquo;est pas encore pour tout de suite, vu qu&rsquo;aucune date de sortie n&rsquo;est annonc\u00e9e pour ce film. Dommage.<\/p>\n<p>En tous cas, \u00e7a fait plaisir de voir enfin des bons films asiatiques qui sortent au cin\u00e9ma et dans toutes les salles (ou presque, car \u00e0 Toulouse il n&rsquo;\u00e9tait que dans un cin\u00e9ma de banlieue pour une tr\u00e8s courte dur\u00e9e et j&rsquo;ai bien faillit le rater T__T). Il faut remercier le festival de Cannes, car, les films qui y sont pr\u00e9sent\u00e9s ont de grandes chances de b\u00e9n\u00e9ficier d&rsquo;une bonne sortie par la suite (alors que tant d&rsquo;autres passent \u00e0 la trappe).<\/p>\n<p><strong>Kim Jee-Woon<\/strong> nous offre donc un vrai bon western et un v\u00e9ritable hommage au grand du genre avec son <strong>Le Bon, La Brute, Le Cingl\u00e9<\/strong>. Un tr\u00e8s bon moment de cin\u00e9ma. On sent vraiment la patte<em> Cor\u00e9ene<\/em> dans ce film, la violence assez crue, le style dynamique et surtout l&rsquo;humour un peu lourd et d\u00e9cal\u00e9 qui n&rsquo;est pas pour me d\u00e9plaire. Les sc\u00e8nes d&rsquo;actions sont tr\u00e8s r\u00e9ussies et nous entrainent avec elles dans l&rsquo;histoire. La musique quant-\u00e0-elle est tout bonnement excellente, bien que certains morceaux soient chapard\u00e9s \u00e0 droite \u00e0 gauche, notamment le remix du tr\u00e8s bon <em>\u00ab\u00a0Don&rsquo;t let me be misunderstood\u00a0\u00bb<\/em> qu&rsquo;on entend aussi dans <strong>Kill Bill<\/strong>. Le trio de personnages principaux, tous plus classes les uns que les autres, vont surement donner envie \u00e0 certains d&rsquo;entre vous de remettre le port de la moustache au gout du jour ^__~!!<\/p>\n<p style=\"text-align: center;\"><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/bon_brute_cingle_eng.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-886 aligncenter\" title=\"bon_brute_cingle_eng\" src=\"\/wp-content\/images\/2009\/02\/bon_brute_cingle_eng-150x150.jpg\" alt=\"bon_brute_cingle_eng\" width=\"150\" height=\"150\" \/><\/a><br \/>\n<em>J&rsquo;aime bien l&rsquo;affiche am\u00e9ciraine<\/em><\/p>\n<p>Il y a malgr\u00e9 tout quelques longueurs et l&rsquo;histoire est parfois un peu bord\u00e9lique, mais cela s&rsquo;explique surement par un remaniement du montage pour l&rsquo;international. Plusieurs sc\u00e8nes ont \u00e9t\u00e9 supprim\u00e9es ce qui change totalement la narration et nous emp\u00eache d&rsquo;en savoir plus sur les motivations des personnages.<\/p>\n<p>Vivement le <em>Director&rsquo;s Cut<\/em> de la sortie DVD!<\/p>\n<p><strong>\u25ba <a title=\"Les Simpson le film\" href=\"http:\/\/www.simpsonsmovie.com\" target=\"_blank\">Les Simpson &#8211; Le film<\/a><\/strong><\/p>\n<p><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/les_simpsons_le_film.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-905 alignleft\" title=\"les_simpsons_le_film\" src=\"\/wp-content\/images\/2009\/02\/les_simpsons_le_film-150x150.jpg\" alt=\"les_simpsons_le_film\" width=\"150\" height=\"150\" \/><\/a>Hmmm que dire sur ce film. Ca ressemble \u00e0 la s\u00e9rie t\u00e9l\u00e9, en plus joli certes, mais avec plein de 3D, et une animation faite par des Cor\u00e9ens, \u00e7a fait bizarre tous ces noms Cor\u00e9ens pendant le g\u00e9n\u00e9rique de fin, on se demande si les Simpson ont pas \u00e9t\u00e9 rachet\u00e9s ^^;. C&rsquo;est plut\u00f4t bien fait, c&rsquo;est dr\u00f4le, \u00e7a passe le temps mais rien de super emballant ceci dit, juste une nouvelle d\u00e9clinaison des aventures de la famille<strong> Simspon<\/strong>, rien de plus. D&rsquo;habitude, <strong>Homer<\/strong>, avec qui je veux me marier (tiens, je l&rsquo;ai oubli\u00e9 dans mon post<em> \u00ab\u00a0mes ch\u00e9ris imaginaires\u00a0\u00bb<\/em> huhu), est, certes, un \u00e9go\u00efste, maladroit, feignant, alcoolique, stupide et tout ce qu&rsquo;on veut, mais il a un bon fond et je l&rsquo;aime bien. L\u00e0, il est un peu trop d\u00e9crit comme un connard sans scrupule et je n&rsquo;aime pas ce remaniement de personnage. <strong>Bart<\/strong> lui aussi n&rsquo;a pas vraiment le m\u00eame caract\u00e8re et \u00e7a m&rsquo;a un peu g\u00ean\u00e9.<\/p>\n<p>Voila, rien de plus \u00e0 dire, \u00e0 part que la <strong>Fox<\/strong> avait r\u00e9serv\u00e9 le nom de domaine pour le site internet attach\u00e9 au film depuis 1997 (ils sont pr\u00e9voyant et ne voulaient pas se faire avoir ^^)!<\/p>\n<p><strong>\u25ba Un jour sans fin<\/strong><\/p>\n<p><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/jour_sans_fin.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-925 alignleft\" title=\"jour_sans_fin\" src=\"\/wp-content\/images\/2009\/02\/jour_sans_fin-150x150.jpg\" alt=\"jour_sans_fin\" width=\"150\" height=\"150\" \/><\/a>J&rsquo;adore ce film&#8230; Je l&rsquo;ai vu plusieurs fois, mais croyez le ou non, je n&rsquo;avais jamais vu la fin, car la cassette vid\u00e9o sur laquelle le film avait \u00e9t\u00e9 enregistr\u00e9 s&rsquo;arr\u00eatait avant la fin du film. <strong>Bill Murray<\/strong> tourne sa sculpture de glace vers une <strong>Andie MacDowell<\/strong> \u00e9mue et BIM, \u00e7a rembobine ^^; Il aurait pu s&rsquo;appeler pour moi <em>\u00ab\u00a0Un film sans fin\u00a0\u00bb<\/em>.<br \/>\nRien a redire sur ce film (je l&rsquo;ai d\u00e9j\u00e0 bri\u00e8vement \u00e9voqu\u00e9 <a title=\"post sironimo - jour de la marmotte\" href=\"\/index.php\/2009\/02\/02\/le-jour-de-la-marmotte\/\" target=\"_blank\">dans ce post<\/a>), \u00e0 part que j&rsquo;avais oubli\u00e9 combien <strong>Andie MacDowell<\/strong> est quand m\u00eame une actrice super cucul la praline. L&rsquo;affiche est affreuse et <strong>Bill Murray<\/strong> se serait fait mordre deux fois par une marmotte durant le tournage, \u00e7a se laisse pas faire ces b\u00eates l\u00e0 ^__~! J&rsquo;ai enfin vu la fin et d\u00e9couvert comment il se sort de ce cauchemar, ouaiis \\o\/!<\/p>\n<p><strong>\u25ba <a title=\"Little Miss Sunshine Official website\" href=\"http:\/\/www.foxsearchlight.com\/littlemisssunshine\/\" target=\"_blank\">Little Miss Sunshine<\/a><\/strong><\/p>\n<p><a class=\"lytebox\" href=\"\/wp-content\/images\/2009\/02\/little_miss_sunshine.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-928 alignleft\" title=\"little_miss_sunshine\" src=\"\/wp-content\/images\/2009\/02\/little_miss_sunshine-150x150.jpg\" alt=\"little_miss_sunshine\" width=\"150\" height=\"150\" \/><\/a>Depuis le temps que je devais le voir ce film. A chaque fois on m&rsquo;amenait le DVD et on ne trouvait finalement pas le temps de le regarder :\/<br \/>\nUne tr\u00e8s belle et simple histoire familiale. Une sorte de <em>road movie<\/em> o\u00f9, au fil de la route, chacun peut se perdre ou au contraire se retrouver lui-m\u00eame.<br \/>\nLe fait que tout le monde me parle de ce film, tout le bien que j&rsquo;en ai entendu et les nombreux prix qu&rsquo;il a gagn\u00e9, a fait que je ne m&rsquo;attendais pas \u00e0 quelque-chose d&rsquo;aussi&#8230;Simple et prenant en fait.<br \/>\nIl y a un petit cot\u00e9 d\u00e9cal\u00e9, un humour fin et des personnages si normaux et atypiques \u00e0 la fois, que le tout m&rsquo;a beaucoup \u00e9voqu\u00e9 les films de <strong>Wes Anderson<\/strong> je dois dire.<br \/>\nOn a l\u00e0 un beau portrait d&rsquo;une famille \u00e0 la d\u00e9rive qui pourtant ne l&rsquo;est pas tant que \u00e7a. Lorsqu&rsquo;on est diff\u00e9rent de ce que l&rsquo;on attend de nous c&rsquo;est \u00e9videment difficile mais c&rsquo;est aussi une force. C&rsquo;est \u00e9mouvant, c&rsquo;est rigolo, c&rsquo;est plein d&rsquo;espoir. La musique est elle aussi tr\u00e8s chouette. Bref, un tr\u00e8s bon film.<\/p>\n<p>Je finirais en disant : merci aux Fran\u00e7ais de ne pas avoir traduit le titre pour une fois!! Parce que <em>\u00ab\u00a0Petite Miss Soleil brillant\u00a0\u00bb<\/em> non merci ^^;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olalalla c&rsquo;est catastrophique&#8230; Avant je parlais un peu des films que j&rsquo;allais voir au cin\u00e9 ou m\u00eame des films vus en DVD ou \u00e0 la t\u00e9l\u00e9, j&rsquo;avais m\u00eame cr\u00e9er un blog sp\u00e9cialement pour \u00e7a. Et puis, j&rsquo;ai eu l&rsquo;impression que &hellip; <a href=\"https:\/\/sironimo.com\/index.php\/2009\/02\/18\/derniers-films-vus-part-1\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[68,51],"_links":{"self":[{"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/posts\/878"}],"collection":[{"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/comments?post=878"}],"version-history":[{"count":66,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/posts\/878\/revisions"}],"predecessor-version":[{"id":950,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/posts\/878\/revisions\/950"}],"wp:attachment":[{"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sironimo.com\/index.php\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}